{"id":239915,"date":"2018-11-28T10:43:00","date_gmt":"2018-11-28T10:43:00","guid":{"rendered":"https:\/\/lightsourcebp.com\/?p=239915"},"modified":"2023-07-24T08:31:28","modified_gmt":"2023-07-24T08:31:28","slug":"lightsource-bp-anuncia-expansao-no-brasil-new","status":"publish","type":"post","link":"https:\/\/lightsourcebp.com\/br\/news\/lightsource-bp-anuncia-expansao-no-brasil-new\/","title":{"rendered":"Lightsource BP anuncia expans\u00e3o no Brasil"},"content":{"rendered":"<div style=\"margin-top: 0px; margin-bottom: 0px;\" class=\"sharethis-inline-share-buttons\" ><\/div><section class=\"block-page-title bg-color-white\">\n  <div class=\"pt-60 pt-lg-100\"><\/div>\n\n  <div class=\"container\">\n    <div class=\"row\">\n      <div class=\"col-12\">\n                <h1 class=\"fg-color-gradient\">Lightsource BP anuncia expans\u00e3o no Brasil<\/h1>\n      <\/div>\n    <\/div>\n  <\/div>\n\n  <div class=\"pt-60 pt-lg-100\"><\/div>\n<\/section>\n  \n\n\n<section class=\"banner-single position-relative\">\n  <div class=\"container-fluid\">\n    <div class=\"row\">\n      <div class=\"col-12 px-0\">\n                <div class=\"position-relative w-100 h-100 aspect-ratio-banner object-fit-cover\">\n          <picture>\n                    <source srcset=\"https:\/\/lightsourcebp.com\/app\/uploads\/2022\/12\/IL20181128161355-american-public-power-association-419672-unsplash-1920x800-1-450x188.jpg, https:\/\/lightsourcebp.com\/app\/uploads\/2022\/12\/IL20181128161355-american-public-power-association-419672-unsplash-1920x800-1-1000x417.jpg 2x\"\n                          media=\"(max-width: 575px)\">\n                    <source srcset=\"https:\/\/lightsourcebp.com\/app\/uploads\/2022\/12\/IL20181128161355-american-public-power-association-419672-unsplash-1920x800-1-1000x417.jpg, https:\/\/lightsourcebp.com\/app\/uploads\/2022\/12\/IL20181128161355-american-public-power-association-419672-unsplash-1920x800-1.jpg 2x\"\n                          media=\"(min-width: 576px) and (max-width: 991px)\">\n                    <source srcset=\"https:\/\/lightsourcebp.com\/app\/uploads\/2022\/12\/IL20181128161355-american-public-power-association-419672-unsplash-1920x800-1.jpg, https:\/\/lightsourcebp.com\/app\/uploads\/2022\/12\/IL20181128161355-american-public-power-association-419672-unsplash-1920x800-1.jpg 2x\"\n                          media=\"(min-width: 992px)\">\n                    <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lightsourcebp.com\/app\/uploads\/2022\/12\/IL20181128161355-american-public-power-association-419672-unsplash-1920x800-1.jpg\" alt=\"\"\n                       srcset=\"https:\/\/lightsourcebp.com\/app\/uploads\/2022\/12\/IL20181128161355-american-public-power-association-419672-unsplash-1920x800-1.jpg 2x\"\n                       sizes=\"auto, 100vw\"\n                       class=\"position-absolute w-100 h-100 left-0 top-0 object-fit-cover\"\n                       width=\"1920\"\n                       height=\"800\">\n                <\/picture>\n        <\/div>\n              <\/div>\n    <\/div>\n  <\/div>\n<\/section>\n\n\n<section class=\"text align block_6920bf24794bc795c93e1a5ae3f47e12 block bg-color-white position-relative z-1 overflow-hidden\">\n    <div class=\"pt-60 pt-lg-100\"><\/div>\n\n  \n  <div class=\"container \">\n    <div class=\"row\">\n      <div class=\"col-12\">\n        <span class=\"rich-text standard-text fg-color-navy\">\n          <p>S\u00e3o Paulo, 28 de novembro de 2018 \u2013 A Lightsource BP, l\u00edder mundial no financiamento, desenvolvimento e opera\u00e7\u00f5es de projetos em energia solar de longo prazo, anunciou hoje a sua expans\u00e3o no mercado brasileiro de energia.<\/p>\n<p>A estrat\u00e9gia da Lightsource BP para o Brasil ser\u00e1 focada no desenvolvimento de projetos solares, bem como em solu\u00e7\u00f5es inteligentes para armazenamento de energia para os setores dom\u00e9stico, comercial e industrial do pa\u00eds. Isso permitir\u00e1 que os consumidores acessem suas pr\u00f3prias fontes de energia renov\u00e1vel a um valor reduzido e previs\u00edvel. Simultaneamente, a companhia tamb\u00e9m desenvolver\u00e1 novos projetos solares para pequenas e m\u00e9dias empresas e consumidores locais. A Lightsource BP buscar\u00e1 construir e estabelecer parceria de longo prazo com desenvolvedores regionais a fim de cumprir suas metas.<\/p>\n<p>O Brasil \u00e9 o maior mercado consumidor da Am\u00e9rica Latina, e vem buscando diversificar suas fontes de eletricidade. Sua produ\u00e7\u00e3o de energia renov\u00e1vel atualmente se concentra em grandes projetos hidroel\u00e9tricos, enquanto a energia solar ainda representa um percentual pequeno na matriz energ\u00e9tica do pa\u00eds.<\/p>\n<p>Nick Boyle, CEO do grupo Lightsource BP, comenta: \u201cProjetos de energia solar s\u00e3o flex\u00edveis e relativamente f\u00e1ceis de implementar, o que os torna a escolha ideal para aumento da capacidade de gera\u00e7\u00e3o. N\u00f3s pretendemos potencializar nossa expertise em financiamento e oferecer uma ampla gama de servi\u00e7os para desempenhar um papel de destaque no desenvolvimento da energia solar no Brasil.<\/p>\n<p>N\u00f3s vemos uma grande oportunidade de crescimento no Brasil. Acreditamos que a legisla\u00e7\u00e3o que apoia a energia renov\u00e1vel certamente ter\u00e1 um papel importante. Queremos ser parte do desenvolvimento da energia solar no Brasil, trabalhando com empresas parceiras visando uma eletricidade acess\u00edvel e confi\u00e1vel. Para a Lightsource BP, entrar em novos mercados n\u00e3o est\u00e1 relacionado somente a rentabilidade, mas ao potencial de crescimento e fortalecimento das comunidades e das economias em desenvolvimento. Com o nosso comprovado hist\u00f3rico e nossa habilidade em construir parcerias fortes e confi\u00e1veis , acreditamos que podemos ter um papel muito importante em acrescentar energia solar \u00e0 matriz energ\u00e9tica do Brasil.\u201d<\/p>\n<p>Dev Sanyal, CEO do neg\u00f3cio de Energias Alternativas da BP, disse: \u201cAno passado, a produ\u00e7\u00e3o de energia renov\u00e1vel mundial cresceu por volta de 17% \u2013 um aumento maior que o registrado na m\u00e9dia dos \u00faltimos 10 anos \u2013 com destaque para energia e\u00f3lica e solar. Estamos focados em trabalhar com a Lightsource BP para expandir sua atua\u00e7\u00e3o global e potencializar este crescimento, recorrendo particularmente \u00e0 presen\u00e7a internacional da BP e suas parcerias. Vemos grandes oportunidades em oferecer solu\u00e7\u00f5es de energia acess\u00edveis, confi\u00e1veis e com baixas emiss\u00f5es de carbono, atrav\u00e9s da integra\u00e7\u00e3o da energia solar com os nossos neg\u00f3cios de energia renov\u00e1vel existentes.\u201d<\/p>\n<p>Mario Lindenhayn, Head of Country da BP no Brasil, acrescenta: \u201cCom base em tend\u00eancias recentes, o Energy Outlook da BP projeta um aumento no consumo de energia no Brasil de 60% at\u00e9 2040. Nesse contexto, a participa\u00e7\u00e3o de energias renov\u00e1veis deve crescer at\u00e9 47% gra\u00e7as a um importante aumento em energia solar, e\u00f3lica, hidroel\u00e9trica e a duplica\u00e7\u00e3o do uso de biocombust\u00edveis. A BP j\u00e1 tem uma forte presen\u00e7a aqui no Brasil com nossos neg\u00f3cios de Upstream, Downstream e Biocombust\u00edveis, e estamos satisfeitos em poder acrescentar a energia solar ao nosso portf\u00f3lio no pa\u00eds atrav\u00e9s da Lightsource BP.\u201d<\/p>\n\n        <\/span>\n      <\/div>\n    <\/div>\n  <\/div>\n\n  <div class=\"pt-60 pt-lg-100\"><\/div>\n<\/section>\n\n\n<section class=\"multi-column-cards align block_753d51605c31db8f1d7e9dca3e8ab951 block bg-color-white\">\n  <div class=\"pt-60 pt-lg-100\"><\/div>\n\n  <div class=\"container\">\n    <div class=\"row\">\n      <div class=\"col-12\">\n                <h3 class=\"mb-35\">Not\u00edcias relacionadas<\/h3>\n      <\/div>\n    <\/div>\n    <div class=\"row\">\n                        <div class=\"col-12 col-lg-4 mb-30\">\n  <div class=\"multi-column-cards__image-container h-300px h-lg-250px\">\n    <a href=\"https:\/\/lightsourcebp.com\/br\/news\/lightsource-bp-e-petrobras-consolidam-parceria-estrategica-em-energias-renovaveis-onshore-no-brasil\/\" class=\"d-block w-100 h-100\">\n      <picture><source srcset=\"https:\/\/lightsourcebp.com\/app\/uploads\/2026\/05\/ES-Projects-Vendimia-Banner-aspect-ratio-315-195-1200x743.jpg 1200w, https:\/\/lightsourcebp.com\/app\/uploads\/2026\/05\/ES-Projects-Vendimia-Banner-aspect-ratio-315-195-300x186.jpg 300w, https:\/\/lightsourcebp.com\/app\/uploads\/2026\/05\/ES-Projects-Vendimia-Banner-aspect-ratio-315-195-1024x634.jpg 1024w, https:\/\/lightsourcebp.com\/app\/uploads\/2026\/05\/ES-Projects-Vendimia-Banner-aspect-ratio-315-195-80x50.jpg 80w, https:\/\/lightsourcebp.com\/app\/uploads\/2026\/05\/ES-Projects-Vendimia-Banner-aspect-ratio-315-195-150x93.jpg 150w, https:\/\/lightsourcebp.com\/app\/uploads\/2026\/05\/ES-Projects-Vendimia-Banner-aspect-ratio-315-195-450x279.jpg 450w, https:\/\/lightsourcebp.com\/app\/uploads\/2026\/05\/ES-Projects-Vendimia-Banner-aspect-ratio-315-195-767x475.jpg 767w, https:\/\/lightsourcebp.com\/app\/uploads\/2026\/05\/ES-Projects-Vendimia-Banner-aspect-ratio-315-195-1000x619.jpg 1000w, https:\/\/lightsourcebp.com\/app\/uploads\/2026\/05\/ES-Projects-Vendimia-Banner-aspect-ratio-315-195.jpg 1292w\" sizes=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lightsourcebp.com\/app\/uploads\/2026\/05\/ES-Projects-Vendimia-Banner-aspect-ratio-315-195-1200x743.jpg\" alt=\"\" width=\"1200\" height=\"743\" class=\"w-100 h-100 object-fit-cover\"><\/picture>\n    <\/a>\n  <\/div>\n      <p class=\"mt-20 mb-10 font-size-paragraph-small\">21 May, 2026<\/p>\n    <a class=\"text-decoration-none text-decoration-sm-underline-hover\" href=\"https:\/\/lightsourcebp.com\/br\/news\/lightsource-bp-e-petrobras-consolidam-parceria-estrategica-em-energias-renovaveis-onshore-no-brasil\/\">\n    <h5 class=\"mb-15 fg-color-navy\">Lightsource bp e Petrobras consolidam parceria estrat\u00e9gica em energias renov\u00e1veis onshore no Brasil<\/h5>\n  <\/a>\n      <p class=\"mb-15 line-height-level-6\">Conclus\u00e3o da transa\u00e7\u00e3o refor\u00e7a atua\u00e7\u00e3o da Petrobras em gera\u00e7\u00e3o de energia solar e contribui para a estrat\u00e9gia de crescimento da Lightsource bp no Brasil.<\/p>\n    <p><a href=\"https:\/\/lightsourcebp.com\/br\/news\/lightsource-bp-e-petrobras-consolidam-parceria-estrategica-em-energias-renovaveis-onshore-no-brasil\/\">Leia a hist\u00f3ria <span class=\"ml-10\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"8\" height=\"14\" fill=\"none\"><path stroke=\"currentColor\" stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-width=\"2\" d=\"M1 13l6-6-6-6\"\/><\/svg><\/span><\/a><\/p>\n<\/div>\n                  <div class=\"col-12 col-lg-4 mb-30\">\n  <div class=\"multi-column-cards__image-container h-300px h-lg-250px\">\n    <a href=\"https:\/\/lightsourcebp.com\/br\/news\/lightsource-bp-e-petrobras-anunciam-assinatura-de-parceria-estrategica-no-segmento-de-energia-renovavel-no-brasil\/\" class=\"d-block w-100 h-100\">\n      <picture><source srcset=\"https:\/\/lightsourcebp.com\/app\/uploads\/2025\/12\/BRZ-News-JV-banner-aspect-ratio-315-195-1200x743.jpg 1200w, https:\/\/lightsourcebp.com\/app\/uploads\/2025\/12\/BRZ-News-JV-banner-aspect-ratio-315-195-300x186.jpg 300w, https:\/\/lightsourcebp.com\/app\/uploads\/2025\/12\/BRZ-News-JV-banner-aspect-ratio-315-195-1024x634.jpg 1024w, https:\/\/lightsourcebp.com\/app\/uploads\/2025\/12\/BRZ-News-JV-banner-aspect-ratio-315-195-80x50.jpg 80w, https:\/\/lightsourcebp.com\/app\/uploads\/2025\/12\/BRZ-News-JV-banner-aspect-ratio-315-195-150x93.jpg 150w, https:\/\/lightsourcebp.com\/app\/uploads\/2025\/12\/BRZ-News-JV-banner-aspect-ratio-315-195-450x279.jpg 450w, https:\/\/lightsourcebp.com\/app\/uploads\/2025\/12\/BRZ-News-JV-banner-aspect-ratio-315-195-767x475.jpg 767w, https:\/\/lightsourcebp.com\/app\/uploads\/2025\/12\/BRZ-News-JV-banner-aspect-ratio-315-195-1000x619.jpg 1000w, https:\/\/lightsourcebp.com\/app\/uploads\/2025\/12\/BRZ-News-JV-banner-aspect-ratio-315-195.jpg 1292w\" sizes=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lightsourcebp.com\/app\/uploads\/2025\/12\/BRZ-News-JV-banner-aspect-ratio-315-195-1200x743.jpg\" alt=\"\" width=\"1200\" height=\"743\" class=\"w-100 h-100 object-fit-cover\"><\/picture>\n    <\/a>\n  <\/div>\n      <p class=\"mt-20 mb-10 font-size-paragraph-small\">17 Dec, 2025<\/p>\n    <a class=\"text-decoration-none text-decoration-sm-underline-hover\" href=\"https:\/\/lightsourcebp.com\/br\/news\/lightsource-bp-e-petrobras-anunciam-assinatura-de-parceria-estrategica-no-segmento-de-energia-renovavel-no-brasil\/\">\n    <h5 class=\"mb-15 fg-color-navy\">Lightsource bp e Petrobras anunciam assinatura de parceria estrat\u00e9gica no segmento de energia renov\u00e1vel no Brasil<\/h5>\n  <\/a>\n      <p class=\"mb-15 line-height-level-6\">Movimento impulsiona atua\u00e7\u00e3o da Petrobras em energias renov\u00e1veis, visando acelerar projetos solares e contribui para a estrat\u00e9gia de crescimento da Lightsource bp no Brasil<\/p>\n    <p><a href=\"https:\/\/lightsourcebp.com\/br\/news\/lightsource-bp-e-petrobras-anunciam-assinatura-de-parceria-estrategica-no-segmento-de-energia-renovavel-no-brasil\/\">Leia a hist\u00f3ria <span class=\"ml-10\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"8\" height=\"14\" fill=\"none\"><path stroke=\"currentColor\" stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-width=\"2\" d=\"M1 13l6-6-6-6\"\/><\/svg><\/span><\/a><\/p>\n<\/div>\n                  <div class=\"col-12 col-lg-4 mb-30\">\n  <div class=\"multi-column-cards__image-container h-300px h-lg-250px\">\n    <a href=\"https:\/\/lightsourcebp.com\/br\/news\/lightsource-bp-promove-programacao-especial-em-comemoracao-ao-mes-das-criancas\/\" class=\"d-block w-100 h-100\">\n      <picture><source srcset=\"https:\/\/lightsourcebp.com\/app\/uploads\/2025\/11\/BRA-News-Childrens-day-2025-banner-aspect-ratio-315-195-1200x743.jpg 1200w, https:\/\/lightsourcebp.com\/app\/uploads\/2025\/11\/BRA-News-Childrens-day-2025-banner-aspect-ratio-315-195-300x186.jpg 300w, https:\/\/lightsourcebp.com\/app\/uploads\/2025\/11\/BRA-News-Childrens-day-2025-banner-aspect-ratio-315-195-1024x634.jpg 1024w, https:\/\/lightsourcebp.com\/app\/uploads\/2025\/11\/BRA-News-Childrens-day-2025-banner-aspect-ratio-315-195-80x50.jpg 80w, https:\/\/lightsourcebp.com\/app\/uploads\/2025\/11\/BRA-News-Childrens-day-2025-banner-aspect-ratio-315-195-150x93.jpg 150w, https:\/\/lightsourcebp.com\/app\/uploads\/2025\/11\/BRA-News-Childrens-day-2025-banner-aspect-ratio-315-195-450x279.jpg 450w, https:\/\/lightsourcebp.com\/app\/uploads\/2025\/11\/BRA-News-Childrens-day-2025-banner-aspect-ratio-315-195-767x475.jpg 767w, https:\/\/lightsourcebp.com\/app\/uploads\/2025\/11\/BRA-News-Childrens-day-2025-banner-aspect-ratio-315-195-1000x619.jpg 1000w, https:\/\/lightsourcebp.com\/app\/uploads\/2025\/11\/BRA-News-Childrens-day-2025-banner-aspect-ratio-315-195.jpg 1292w\" sizes=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lightsourcebp.com\/app\/uploads\/2025\/11\/BRA-News-Childrens-day-2025-banner-aspect-ratio-315-195-1200x743.jpg\" alt=\"\" width=\"1200\" height=\"743\" class=\"w-100 h-100 object-fit-cover\"><\/picture>\n    <\/a>\n  <\/div>\n      <p class=\"mt-20 mb-10 font-size-paragraph-small\">28 Nov, 2025<\/p>\n    <a class=\"text-decoration-none text-decoration-sm-underline-hover\" href=\"https:\/\/lightsourcebp.com\/br\/news\/lightsource-bp-promove-programacao-especial-em-comemoracao-ao-mes-das-criancas\/\">\n    <h5 class=\"mb-15 fg-color-navy\">Lightsource bp promove programa\u00e7\u00e3o especial em comemora\u00e7\u00e3o ao m\u00eas das crian\u00e7as<\/h5>\n  <\/a>\n      <p class=\"mb-15 line-height-level-6\">A Lightsource bp realizou uma s\u00e9rie de confraterniza\u00e7\u00f5es que beneficiaram 278 crian\u00e7as de tr\u00eas escolas pr\u00f3ximas ao Complexo Solar Milagres<\/p>\n    <p><a href=\"https:\/\/lightsourcebp.com\/br\/news\/lightsource-bp-promove-programacao-especial-em-comemoracao-ao-mes-das-criancas\/\">Leia a hist\u00f3ria <span class=\"ml-10\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"8\" height=\"14\" fill=\"none\"><path stroke=\"currentColor\" stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-width=\"2\" d=\"M1 13l6-6-6-6\"\/><\/svg><\/span><\/a><\/p>\n<\/div>\n                  <\/div>\n  <\/div>\n\n  <div class=\"pt-60 pt-lg-100\"><\/div>\n<\/section>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":33,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[92],"tags":[],"filter_by":[],"filter_tags":[],"class_list":["post-239915","post","type-post","status-publish","format-standard","hentry","category-uncategorized-us"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/lightsourcebp.com\/br\/wp-json\/wp\/v2\/posts\/239915","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lightsourcebp.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lightsourcebp.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lightsourcebp.com\/br\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/lightsourcebp.com\/br\/wp-json\/wp\/v2\/comments?post=239915"}],"version-history":[{"count":6,"href":"https:\/\/lightsourcebp.com\/br\/wp-json\/wp\/v2\/posts\/239915\/revisions"}],"predecessor-version":[{"id":299688,"href":"https:\/\/lightsourcebp.com\/br\/wp-json\/wp\/v2\/posts\/239915\/revisions\/299688"}],"wp:attachment":[{"href":"https:\/\/lightsourcebp.com\/br\/wp-json\/wp\/v2\/media?parent=239915"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lightsourcebp.com\/br\/wp-json\/wp\/v2\/categories?post=239915"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lightsourcebp.com\/br\/wp-json\/wp\/v2\/tags?post=239915"},{"taxonomy":"filter_by","embeddable":true,"href":"https:\/\/lightsourcebp.com\/br\/wp-json\/wp\/v2\/filter_by?post=239915"},{"taxonomy":"filter_tags","embeddable":true,"href":"https:\/\/lightsourcebp.com\/br\/wp-json\/wp\/v2\/filter_tags?post=239915"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}