{"id":485880,"date":"2026-05-27T12:24:03","date_gmt":"2026-05-27T12:24:03","guid":{"rendered":"https:\/\/lightsourcebp.com\/?p=485880"},"modified":"2026-05-27T12:24:04","modified_gmt":"2026-05-27T12:24:04","slug":"lightsource-bp-estabelece-parceria-com-animob-e-bioinsight-ecoa-para-integrar-pastoreio-local-em-projeto-solar-na-beira-baixa","status":"publish","type":"post","link":"https:\/\/lightsourcebp.com\/pt\/news\/lightsource-bp-estabelece-parceria-com-animob-e-bioinsight-ecoa-para-integrar-pastoreio-local-em-projeto-solar-na-beira-baixa\/","title":{"rendered":"Lightsource bp estabelece parceria com ANIMOB e Bioinsight &amp; ECOA para integrar pastoreio local em projeto solar na Beira Baixa"},"content":{"rendered":"<div style=\"margin-top: 0px; margin-bottom: 0px;\" class=\"sharethis-inline-share-buttons\" ><\/div><section class=\"block-page-title bg-color-white\">\n  <div class=\"pt-60 pt-lg-100\"><\/div>\n\n  <div class=\"container\">\n    <div class=\"row\">\n      <div class=\"col-12\">\n                <h1 class=\"fg-color-gradient\">Lightsource bp estabelece parceria com ANIMOB e Bioinsight &amp; ECOA para integrar pastoreio local em projeto solar na Beira Baixa<\/h1>\n      <\/div>\n    <\/div>\n  <\/div>\n\n  <div class=\"pt-60 pt-lg-100\"><\/div>\n<\/section>\n  \n\n\n<section class=\"banner-single position-relative\">\n  <div class=\"container-fluid\">\n    <div class=\"row\">\n      <div class=\"col-12 px-0\">\n                <div class=\"position-relative w-100 h-100 aspect-ratio-banner object-fit-cover\">\n          <picture>\n                    <source srcset=\"https:\/\/lightsourcebp.com\/app\/uploads\/2026\/05\/PRT-News-ANIMOB-Partnership-Banner-aspect-ratio-417-234-450x252.jpg, https:\/\/lightsourcebp.com\/app\/uploads\/2026\/05\/PRT-News-ANIMOB-Partnership-Banner-aspect-ratio-417-234-1000x561.jpg 2x\"\n                          media=\"(max-width: 575px)\">\n                    <source srcset=\"https:\/\/lightsourcebp.com\/app\/uploads\/2026\/05\/PRT-News-ANIMOB-Partnership-Banner-1000x400.jpg, https:\/\/lightsourcebp.com\/app\/uploads\/2026\/05\/PRT-News-ANIMOB-Partnership-Banner-1920x768.jpg 2x\"\n                          media=\"(min-width: 576px) and (max-width: 991px)\">\n                    <source srcset=\"https:\/\/lightsourcebp.com\/app\/uploads\/2026\/05\/PRT-News-ANIMOB-Partnership-Banner.jpg, https:\/\/lightsourcebp.com\/app\/uploads\/2026\/05\/PRT-News-ANIMOB-Partnership-Banner.jpg 2x\"\n                          media=\"(min-width: 992px)\">\n                    <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lightsourcebp.com\/app\/uploads\/2026\/05\/PRT-News-ANIMOB-Partnership-Banner.jpg\" alt=\"\"\n                       srcset=\"https:\/\/lightsourcebp.com\/app\/uploads\/2026\/05\/PRT-News-ANIMOB-Partnership-Banner.jpg 2x\"\n                       sizes=\"auto, 100vw\"\n                       class=\"position-absolute w-100 h-100 left-0 top-0 object-fit-cover\"\n                       width=\"2000\"\n                       height=\"800\">\n                <\/picture>\n        <\/div>\n              <\/div>\n    <\/div>\n  <\/div>\n<\/section>\n\n\n<section class=\"text align block_acf-block-6a16e2630f6db block bg-color-white position-relative z-1 overflow-hidden\">\n    <div class=\"pt-50 pt-lg-50\"><\/div>\n\n  \n  <div class=\"container \">\n    <div class=\"row\">\n      <div class=\"col-12\">\n        <span class=\"rich-text standard-text fg-color-navy\">\n          <p><strong>A Lightsource bp estabeleceu uma parceria com a ANIMOB e Bioinsight &amp; ECOA com o objetivo de aliar a produ\u00e7\u00e3o de energia renov\u00e1vel com o pastoreio e utiliza\u00e7\u00e3o rent\u00e1vel do solo no projeto solar de Sophia, na Beira Baixa<\/strong>. No \u00e2mbito desta parceria, est\u00e1 a ser desenvolvido um Plano Estrat\u00e9gico de Integra\u00e7\u00e3o Agroecol\u00f3gica e Pastoreio, que visa integrar a central solar no territ\u00f3rio envolvente e promover uma gest\u00e3o ativa do solo e da vegeta\u00e7\u00e3o.<\/p>\n<p>A abordagem proposta assenta na utiliza\u00e7\u00e3o de pastoreio rotativo, com recurso \u00e0 mobilidade de rebanhos, apoiada por uma plataforma interativa que liga produtores pecu\u00e1rios e propriet\u00e1rios de terrenos, permitindo adaptar a gest\u00e3o da vegeta\u00e7\u00e3o \u00e0s caracter\u00edsticas de cada parcela e reduzir a necessidade de interven\u00e7\u00e3o mec\u00e2nica. A solu\u00e7\u00e3o proposta pretende valorizar terrenos atualmente pouco explorados, contribuindo para a melhoria das condi\u00e7\u00f5es e regenera\u00e7\u00e3o dos solos, promo\u00e7\u00e3o da biodiversidade e cria\u00e7\u00e3o de oportunidades econ\u00f3micas para todas as fileiras agroindustriais associadas \u00e0 agropecu\u00e1ria.<\/p>\n<p>O projeto desenvolvido pela ANIMOB poder\u00e1 gerar impacto em toda a cadeia de valor agroindustrial associada ao pastoreio, n\u00e3o apenas na componente pecu\u00e1ria diretamente ligada \u00e0 gest\u00e3o dos rebanhos, mas tamb\u00e9m em atividades como a produ\u00e7\u00e3o de leite e na ind\u00fastria transformadora que dela depende, incluindo produtos tradicionais locais, como o queijo. A iniciativa pretende assim contribuir para o desenvolvimento rural, atrav\u00e9s do envolvimento de produtores e associa\u00e7\u00f5es locais. Tamb\u00e9m ser\u00e1 promovida a redu\u00e7\u00e3o do risco de inc\u00eandio, atrav\u00e9s de uma gest\u00e3o ativa da vegeta\u00e7\u00e3o.<\/p>\n<p>\u201c<em>A forma como desenvolvemos os nossos projetos passa por encontrar solu\u00e7\u00f5es que se adaptem ao territ\u00f3rio e que criem valor local<\/em>\u201d, afirma <strong>Miguel Lobo, Country Manager da Lightsource bp em Portugal<\/strong>. \u201c<em>Neste caso, estamos a trabalhar numa abordagem que permite gerir o espa\u00e7o de forma mais eficiente e sustent\u00e1vel, ao mesmo tempo que refor\u00e7a a liga\u00e7\u00e3o \u00e0s comunidades locais<\/em>\u201d, acrescenta.<\/p>\n<p>A utiliza\u00e7\u00e3o de pastoreio planeado poder\u00e1 ainda contribuir para reduzir a necessidade de interven\u00e7\u00e3o mec\u00e2nica na gest\u00e3o dos terrenos, diminuindo emiss\u00f5es, poeiras e impactos sobre o solo e as infraestruturas, enquanto cria oportunidades para produtores locais.<\/p>\n<p>\u201c<em>Este modelo permite demonstrar que \u00e9 poss\u00edvel conciliar produ\u00e7\u00e3o energ\u00e9tica com pr\u00e1ticas agr\u00edcolas baseadas na regenera\u00e7\u00e3o do solo. Ao ligar produtores e territ\u00f3rio, procuramos desenvolver uma solu\u00e7\u00e3o que responda simultaneamente a desafios ambientais e econ\u00f3micos<\/em>\u201d, refere <strong>Jo\u00e3o Xavier, Fundador da ANIMOB<\/strong>.<\/p>\n<p>A parceria com a ANIMOB e Bioinsight &amp; ECOA enquadra-se na estrat\u00e9gia da Lightsource bp de desenvolver projetos que integrem benef\u00edcios ambientais e sociais nos territ\u00f3rios onde est\u00e1 presente, procurando solu\u00e7\u00f5es adaptadas \u00e0s caracter\u00edsticas locais e com potencial de aplica\u00e7\u00e3o futura noutros projetos em Portugal.<\/p>\n<p>O modelo est\u00e1 a ser desenvolvido no contexto do projeto Sophia, podendo vir a ser adaptado a outros projetos da empresa, em fun\u00e7\u00e3o das especificidades de cada territ\u00f3rio.<\/p>\n<p>Convidamos os produtores locais a <a href=\"https:\/\/www.animob.pt\/contactos\">contactarem a ANIMOB<\/a> para participar desta iniciativa.<\/p>\n\n        <\/span>\n      <\/div>\n    <\/div>\n  <\/div>\n\n  <div class=\"pt-30 pt-lg-30\"><\/div>\n<\/section>\n\n\n<section class=\"multi-column-cards align block_acf-block-6a16e263101e6 block bg-color-white\">\n  <div class=\"pt-30 pt-lg-30\"><\/div>\n\n  <div class=\"container\">\n    <div class=\"row\">\n      <div class=\"col-12\">\n                <h3 class=\"mb-35\">Not\u00edcias<\/h3>\n      <\/div>\n    <\/div>\n    <div class=\"row\">\n                        <div class=\"col-12 col-lg-4 mb-30\">\n  <div class=\"multi-column-cards__image-container h-300px h-lg-250px\">\n    <a href=\"https:\/\/lightsourcebp.com\/pt\/news\/lightsource-bp-e-meta-fortalecem-parceria-com-novo-contrato-de-aquisicao-de-energia-nos-estados-unidos\/\" class=\"d-block w-100 h-100\">\n      <picture><source srcset=\"https:\/\/lightsourcebp.com\/app\/uploads\/2026\/07\/Bellflower-Solar-Gallery-image-7-aspect-ratio-315-195-1200x743.jpg 1200w, https:\/\/lightsourcebp.com\/app\/uploads\/2026\/07\/Bellflower-Solar-Gallery-image-7-aspect-ratio-315-195-300x186.jpg 300w, https:\/\/lightsourcebp.com\/app\/uploads\/2026\/07\/Bellflower-Solar-Gallery-image-7-aspect-ratio-315-195-1024x634.jpg 1024w, https:\/\/lightsourcebp.com\/app\/uploads\/2026\/07\/Bellflower-Solar-Gallery-image-7-aspect-ratio-315-195-80x50.jpg 80w, https:\/\/lightsourcebp.com\/app\/uploads\/2026\/07\/Bellflower-Solar-Gallery-image-7-aspect-ratio-315-195-150x93.jpg 150w, https:\/\/lightsourcebp.com\/app\/uploads\/2026\/07\/Bellflower-Solar-Gallery-image-7-aspect-ratio-315-195-450x279.jpg 450w, https:\/\/lightsourcebp.com\/app\/uploads\/2026\/07\/Bellflower-Solar-Gallery-image-7-aspect-ratio-315-195-767x475.jpg 767w, https:\/\/lightsourcebp.com\/app\/uploads\/2026\/07\/Bellflower-Solar-Gallery-image-7-aspect-ratio-315-195-1000x619.jpg 1000w, https:\/\/lightsourcebp.com\/app\/uploads\/2026\/07\/Bellflower-Solar-Gallery-image-7-aspect-ratio-315-195-1600x990.jpg 1600w, https:\/\/lightsourcebp.com\/app\/uploads\/2026\/07\/Bellflower-Solar-Gallery-image-7-aspect-ratio-315-195-1920x1188.jpg 1920w\" sizes=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lightsourcebp.com\/app\/uploads\/2026\/07\/Bellflower-Solar-Gallery-image-7-aspect-ratio-315-195-1200x743.jpg\" alt=\"\" width=\"1200\" height=\"743\" class=\"w-100 h-100 object-fit-cover\"><\/picture>\n    <\/a>\n  <\/div>\n      <p class=\"mt-20 mb-10 font-size-paragraph-small\">24 Jul, 2026<\/p>\n    <a class=\"text-decoration-none text-decoration-sm-underline-hover\" href=\"https:\/\/lightsourcebp.com\/pt\/news\/lightsource-bp-e-meta-fortalecem-parceria-com-novo-contrato-de-aquisicao-de-energia-nos-estados-unidos\/\">\n    <h5 class=\"mb-15 fg-color-navy\">Lightsource bp e Meta fortalecem parceria com novo contrato de aquisi\u00e7\u00e3o de energia nos Estados Unidos<\/h5>\n  <\/a>\n      <p class=\"mb-15 line-height-level-6\">A Meta assinou um contrato de aquisi\u00e7\u00e3o de energia (PPA) com a Lightsource bp associado ao novo projeto do Parque Fotovoltaico Mowata, no Louisiana (Estados Unidos).<\/p>\n    <p><a href=\"https:\/\/lightsourcebp.com\/pt\/news\/lightsource-bp-e-meta-fortalecem-parceria-com-novo-contrato-de-aquisicao-de-energia-nos-estados-unidos\/\">Leia a hist\u00f3ria <span class=\"ml-10\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"8\" height=\"14\" fill=\"none\"><path stroke=\"currentColor\" stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-width=\"2\" d=\"M1 13l6-6-6-6\"\/><\/svg><\/span><\/a><\/p>\n<\/div>\n                  <div class=\"col-12 col-lg-4 mb-30\">\n  <div class=\"multi-column-cards__image-container h-300px h-lg-250px\">\n    <a href=\"https:\/\/lightsourcebp.com\/pt\/news\/lightsource-bp-e-adene-estabelecem-parceria-para-promover-a-literacia-energetica-e-apoiar-a-transicao-energetica-em-portugal\/\" class=\"d-block w-100 h-100\">\n      <picture><source srcset=\"https:\/\/lightsourcebp.com\/app\/uploads\/2026\/07\/PRT-News-ADENE-Partnership-featured-aspect-ratio-315-195-1200x743.jpg 1200w, https:\/\/lightsourcebp.com\/app\/uploads\/2026\/07\/PRT-News-ADENE-Partnership-featured-aspect-ratio-315-195-300x186.jpg 300w, https:\/\/lightsourcebp.com\/app\/uploads\/2026\/07\/PRT-News-ADENE-Partnership-featured-aspect-ratio-315-195-1024x634.jpg 1024w, https:\/\/lightsourcebp.com\/app\/uploads\/2026\/07\/PRT-News-ADENE-Partnership-featured-aspect-ratio-315-195-80x50.jpg 80w, https:\/\/lightsourcebp.com\/app\/uploads\/2026\/07\/PRT-News-ADENE-Partnership-featured-aspect-ratio-315-195-150x93.jpg 150w, https:\/\/lightsourcebp.com\/app\/uploads\/2026\/07\/PRT-News-ADENE-Partnership-featured-aspect-ratio-315-195-450x279.jpg 450w, https:\/\/lightsourcebp.com\/app\/uploads\/2026\/07\/PRT-News-ADENE-Partnership-featured-aspect-ratio-315-195-767x475.jpg 767w, https:\/\/lightsourcebp.com\/app\/uploads\/2026\/07\/PRT-News-ADENE-Partnership-featured-aspect-ratio-315-195-1000x619.jpg 1000w, https:\/\/lightsourcebp.com\/app\/uploads\/2026\/07\/PRT-News-ADENE-Partnership-featured-aspect-ratio-315-195-1600x991.jpg 1600w, https:\/\/lightsourcebp.com\/app\/uploads\/2026\/07\/PRT-News-ADENE-Partnership-featured-aspect-ratio-315-195.jpg 1854w\" sizes=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lightsourcebp.com\/app\/uploads\/2026\/07\/PRT-News-ADENE-Partnership-featured-aspect-ratio-315-195-1200x743.jpg\" alt=\"\" width=\"1200\" height=\"743\" class=\"w-100 h-100 object-fit-cover\"><\/picture>\n    <\/a>\n  <\/div>\n      <p class=\"mt-20 mb-10 font-size-paragraph-small\">21 Jul, 2026<\/p>\n    <a class=\"text-decoration-none text-decoration-sm-underline-hover\" href=\"https:\/\/lightsourcebp.com\/pt\/news\/lightsource-bp-e-adene-estabelecem-parceria-para-promover-a-literacia-energetica-e-apoiar-a-transicao-energetica-em-portugal\/\">\n    <h5 class=\"mb-15 fg-color-navy\">Lightsource bp e ADENE estabelecem parceria para promover a literacia energ\u00e9tica e apoiar a transi\u00e7\u00e3o energ\u00e9tica em Portugal<\/h5>\n  <\/a>\n      <p class=\"mb-15 line-height-level-6\">A parceria prev\u00ea a\u00e7\u00f5es conjuntas de informa\u00e7\u00e3o, forma\u00e7\u00e3o e sensibiliza\u00e7\u00e3o para refor\u00e7ar a literacia energ\u00e9tica e promover uma participa\u00e7\u00e3o mais informada dos cidad\u00e3os.<\/p>\n    <p><a href=\"https:\/\/lightsourcebp.com\/pt\/news\/lightsource-bp-e-adene-estabelecem-parceria-para-promover-a-literacia-energetica-e-apoiar-a-transicao-energetica-em-portugal\/\">Leia a hist\u00f3ria <span class=\"ml-10\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"8\" height=\"14\" fill=\"none\"><path stroke=\"currentColor\" stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-width=\"2\" d=\"M1 13l6-6-6-6\"\/><\/svg><\/span><\/a><\/p>\n<\/div>\n                  <div class=\"col-12 col-lg-4 mb-30\">\n  <div class=\"multi-column-cards__image-container h-300px h-lg-250px\">\n    <a href=\"https:\/\/lightsourcebp.com\/pt\/news\/celebrando-o-dia-europeu-da-energia-solar\/\" class=\"d-block w-100 h-100\">\n      <picture><source srcset=\"https:\/\/lightsourcebp.com\/app\/uploads\/2026\/06\/2021-04-07-07.29.50-VENDIMIA-Plonsky-Cam-A-1482-Edit-MED-scaled-e1627896791593-3-aspect-ratio-315-195-2-1200x743.jpg 1200w, https:\/\/lightsourcebp.com\/app\/uploads\/2026\/06\/2021-04-07-07.29.50-VENDIMIA-Plonsky-Cam-A-1482-Edit-MED-scaled-e1627896791593-3-aspect-ratio-315-195-2-300x186.jpg 300w, https:\/\/lightsourcebp.com\/app\/uploads\/2026\/06\/2021-04-07-07.29.50-VENDIMIA-Plonsky-Cam-A-1482-Edit-MED-scaled-e1627896791593-3-aspect-ratio-315-195-2-1024x634.jpg 1024w, https:\/\/lightsourcebp.com\/app\/uploads\/2026\/06\/2021-04-07-07.29.50-VENDIMIA-Plonsky-Cam-A-1482-Edit-MED-scaled-e1627896791593-3-aspect-ratio-315-195-2-80x50.jpg 80w, https:\/\/lightsourcebp.com\/app\/uploads\/2026\/06\/2021-04-07-07.29.50-VENDIMIA-Plonsky-Cam-A-1482-Edit-MED-scaled-e1627896791593-3-aspect-ratio-315-195-2-150x93.jpg 150w, https:\/\/lightsourcebp.com\/app\/uploads\/2026\/06\/2021-04-07-07.29.50-VENDIMIA-Plonsky-Cam-A-1482-Edit-MED-scaled-e1627896791593-3-aspect-ratio-315-195-2-450x279.jpg 450w, https:\/\/lightsourcebp.com\/app\/uploads\/2026\/06\/2021-04-07-07.29.50-VENDIMIA-Plonsky-Cam-A-1482-Edit-MED-scaled-e1627896791593-3-aspect-ratio-315-195-2-767x475.jpg 767w, https:\/\/lightsourcebp.com\/app\/uploads\/2026\/06\/2021-04-07-07.29.50-VENDIMIA-Plonsky-Cam-A-1482-Edit-MED-scaled-e1627896791593-3-aspect-ratio-315-195-2-1000x619.jpg 1000w, https:\/\/lightsourcebp.com\/app\/uploads\/2026\/06\/2021-04-07-07.29.50-VENDIMIA-Plonsky-Cam-A-1482-Edit-MED-scaled-e1627896791593-3-aspect-ratio-315-195-2-1600x990.jpg 1600w, https:\/\/lightsourcebp.com\/app\/uploads\/2026\/06\/2021-04-07-07.29.50-VENDIMIA-Plonsky-Cam-A-1482-Edit-MED-scaled-e1627896791593-3-aspect-ratio-315-195-2-1920x1189.jpg 1920w\" sizes=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lightsourcebp.com\/app\/uploads\/2026\/06\/2021-04-07-07.29.50-VENDIMIA-Plonsky-Cam-A-1482-Edit-MED-scaled-e1627896791593-3-aspect-ratio-315-195-2-1200x743.jpg\" alt=\"\" width=\"1200\" height=\"743\" class=\"w-100 h-100 object-fit-cover\"><\/picture>\n    <\/a>\n  <\/div>\n      <p class=\"mt-20 mb-10 font-size-paragraph-small\">19 Jun, 2026<\/p>\n    <a class=\"text-decoration-none text-decoration-sm-underline-hover\" href=\"https:\/\/lightsourcebp.com\/pt\/news\/celebrando-o-dia-europeu-da-energia-solar\/\">\n    <h5 class=\"mb-15 fg-color-navy\">Celebrando o Dia Europeu da Energia Solar<\/h5>\n  <\/a>\n      <p class=\"mb-15 line-height-level-6\">Lightsource bp celebra \u201cSolar Stories\u201d, destacando projetos solares em toda a Europa que abastecem casas, apoiam a biodiversidade e impulsionam a transi\u00e7\u00e3o energ\u00e9tica.<\/p>\n    <p><a href=\"https:\/\/lightsourcebp.com\/pt\/news\/celebrando-o-dia-europeu-da-energia-solar\/\">Leia a hist\u00f3ria <span class=\"ml-10\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"8\" height=\"14\" fill=\"none\"><path stroke=\"currentColor\" stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-width=\"2\" d=\"M1 13l6-6-6-6\"\/><\/svg><\/span><\/a><\/p>\n<\/div>\n                  <\/div>\n  <\/div>\n\n  <div class=\"pt-60 pt-lg-100\"><\/div>\n<\/section>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":53,"featured_media":485882,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[646],"tags":[],"filter_by":[648],"filter_tags":[],"class_list":["post-485880","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-corporate-en-ie-pt","filter_by-press-releases-pt"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/lightsourcebp.com\/pt\/wp-json\/wp\/v2\/posts\/485880","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lightsourcebp.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lightsourcebp.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lightsourcebp.com\/pt\/wp-json\/wp\/v2\/users\/53"}],"replies":[{"embeddable":true,"href":"https:\/\/lightsourcebp.com\/pt\/wp-json\/wp\/v2\/comments?post=485880"}],"version-history":[{"count":5,"href":"https:\/\/lightsourcebp.com\/pt\/wp-json\/wp\/v2\/posts\/485880\/revisions"}],"predecessor-version":[{"id":485889,"href":"https:\/\/lightsourcebp.com\/pt\/wp-json\/wp\/v2\/posts\/485880\/revisions\/485889"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lightsourcebp.com\/pt\/wp-json\/wp\/v2\/media\/485882"}],"wp:attachment":[{"href":"https:\/\/lightsourcebp.com\/pt\/wp-json\/wp\/v2\/media?parent=485880"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lightsourcebp.com\/pt\/wp-json\/wp\/v2\/categories?post=485880"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lightsourcebp.com\/pt\/wp-json\/wp\/v2\/tags?post=485880"},{"taxonomy":"filter_by","embeddable":true,"href":"https:\/\/lightsourcebp.com\/pt\/wp-json\/wp\/v2\/filter_by?post=485880"},{"taxonomy":"filter_tags","embeddable":true,"href":"https:\/\/lightsourcebp.com\/pt\/wp-json\/wp\/v2\/filter_tags?post=485880"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}