{"id":484895,"date":"2026-05-06T14:38:27","date_gmt":"2026-05-06T14:38:27","guid":{"rendered":"https:\/\/lightsourcebp.com\/?post_type=project&#038;p=484895"},"modified":"2026-05-07T14:30:11","modified_gmt":"2026-05-07T14:30:11","slug":"ferme-solaire-des-cazals","status":"publish","type":"project","link":"https:\/\/lightsourcebp.com\/tw\/project\/ferme-solaire-des-cazals\/","title":{"rendered":"Ferme solaire des Cazals"},"content":{"rendered":"<section class=\"block-page-title bg-color-white\">\n  <div class=\"pt-60 pt-lg-100\"><\/div>\n\n  <div class=\"container\">\n    <div class=\"row\">\n      <div class=\"col-12\">\n                <h1 class=\"fg-color-gradient\">Ferme solaire des Cazals<\/h1>\n      <\/div>\n    <\/div>\n  <\/div>\n\n  <div class=\"pt-60 pt-lg-100\"><\/div>\n<\/section>\n  \n\n\n<section class=\"banner-single position-relative\">\n  <div class=\"container-fluid\">\n    <div class=\"row\">\n      <div class=\"col-12 px-0\">\n                <div class=\"position-relative w-100 h-100 aspect-ratio-banner object-fit-cover\">\n          <picture>\n                    <source srcset=\"https:\/\/lightsourcebp.com\/app\/uploads\/2026\/05\/Lightsource-bp_Ferme-Solaire_Cazals_Banner-aspect-ratio-417-234-450x252.png, https:\/\/lightsourcebp.com\/app\/uploads\/2026\/05\/Lightsource-bp_Ferme-Solaire_Cazals_Banner-aspect-ratio-417-234-1000x561.png 2x\"\n                          media=\"(max-width: 575px)\">\n                    <source srcset=\"https:\/\/lightsourcebp.com\/app\/uploads\/2026\/05\/Lightsource-bp_Ferme-Solaire_Cazals_Banner-1000x400.png, https:\/\/lightsourcebp.com\/app\/uploads\/2026\/05\/Lightsource-bp_Ferme-Solaire_Cazals_Banner-1920x768.png 2x\"\n                          media=\"(min-width: 576px) and (max-width: 991px)\">\n                    <source srcset=\"https:\/\/lightsourcebp.com\/app\/uploads\/2026\/05\/Lightsource-bp_Ferme-Solaire_Cazals_Banner.png, https:\/\/lightsourcebp.com\/app\/uploads\/2026\/05\/Lightsource-bp_Ferme-Solaire_Cazals_Banner.png 2x\"\n                          media=\"(min-width: 992px)\">\n                    <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lightsourcebp.com\/app\/uploads\/2026\/05\/Lightsource-bp_Ferme-Solaire_Cazals_Banner.png\" alt=\"\"\n                       srcset=\"https:\/\/lightsourcebp.com\/app\/uploads\/2026\/05\/Lightsource-bp_Ferme-Solaire_Cazals_Banner.png 2x\"\n                       sizes=\"auto, 100vw\"\n                       class=\"position-absolute w-100 h-100 left-0 top-0 object-fit-cover\"\n                       width=\"2000\"\n                       height=\"800\">\n                <\/picture>\n        <\/div>\n              <\/div>\n    <\/div>\n  <\/div>\n<\/section>\n\n\n<section class=\"project-key-numbers align block_acf-block-69fb5ad8ec66d block\">\n  <div class=\"pt-60 pt-lg-100\"><\/div>\n\n  <div class=\"container\">\n        <div class=\"row pb-30 border-top-0 border-right-0 border-left-0 border-bottom-0 border-bottom-md-1px border-solid border-color-beige\">\n              <div class=\"d-flex flex-row flex-wrap\">\n                      <div class=\"d-flex flex-column w-50 w-lg-20 pr-30 pr-sm-50\">\n              <h3 class=\"mb-10\">+ de 6 604 MWh<\/h3>\n              <p class=\"line-height-level-5\">(m\u00e9gawatt heures) d\u2019\u00e9lectricit\u00e9 produite chaque ann\u00e9e<\/p>\n            <\/div>\n                      <div class=\"d-flex flex-column w-50 w-lg-20 pr-30 pr-sm-50\">\n              <h3 class=\"mb-10\">4,97 MWc<\/h3>\n              <p class=\"line-height-level-5\">(m\u00e9gawatts cr\u00eates) de puissance maximale<\/p>\n            <\/div>\n                      <div class=\"d-flex flex-column w-50 w-lg-20 pr-30 pr-sm-50\">\n              <h3 class=\"mb-10\">1 410<\/h3>\n              <p class=\"line-height-level-5\">foyers approvisionn\u00e9s chaque ann\u00e9e (\u00e9quivalent, pour 2,2 personnes\/foyers)<\/p>\n            <\/div>\n                      <div class=\"d-flex flex-column w-50 w-lg-20 pr-30 pr-sm-50\">\n              <h3 class=\"mb-10\">6,6 ha<\/h3>\n              <p class=\"line-height-level-5\">(hectares) de surface cl\u00f4tur\u00e9e<\/p>\n            <\/div>\n                      <div class=\"d-flex flex-column w-50 w-lg-20 \">\n              <h3 class=\"mb-10\">+ de 1 937<\/h3>\n              <p class=\"line-height-level-5\">tonnes de CO2 \u00e9vit\u00e9es chaque ann\u00e9e (estimation compar\u00e9e au mix europ\u00e9en)<\/p>\n            <\/div>\n                  <\/div>\n          <\/div>\n  <\/div>\n\n  <div class=\"pt-60 pt-lg-0\"><\/div>\n<\/section>\n\n\n<section class=\"projects-current-status align block_acf-block-69fb419b827d3 block\">\n  <div class=\"pt-60 pt-lg-100\"><\/div>\n\n  <div class=\"container\">\n        <div class=\"row\">\n              <div class=\"d-flex flex-column flex-lg-row flex-wrap w-100 mb-n300 mb-lg-0\">\n                                  <div class=\"d-flex flex-row flex-lg-column w-100 w-lg-14 h-50px h-lg-auto\">\n              <div class=\"h-50px w-12px h-lg-12px w-lg-100 mb-n12 z-2 bg-color-status-checked position-relative\"><span class=\"\"><svg width=\"15\" height=\"9\" viewbox=\"0 0 11 7\"><path d=\"M1.414 1.414l4 4 4-4\" fill=\"none\" stroke=\"currentColor\" stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-width=\"2\"\/><\/svg><\/span><\/div>\n            <\/div>\n                                              <div class=\"d-flex flex-row flex-lg-column w-100 w-lg-14 h-50px h-lg-auto\">\n              <div class=\"h-50px w-12px h-lg-12px w-lg-100 mb-n12 z-2 bg-color-status-checked position-relative\"><span class=\"\"><svg width=\"15\" height=\"9\" viewbox=\"0 0 11 7\"><path d=\"M1.414 1.414l4 4 4-4\" fill=\"none\" stroke=\"currentColor\" stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-width=\"2\"\/><\/svg><\/span><\/div>\n            <\/div>\n                                                                                                                                            <\/div>\n        <div class=\"d-flex flex-column flex-lg-row w-100 flex-wrap\">\n                      <div class=\"d-flex flex-row flex-lg-column w-100 w-lg-14 flex-middle\">\n              <div class=\"h-50px w-12px h-lg-12px w-lg-100 mb-lg-15 bg-color-status-unchecked position-relative\"><span class=\"\"><svg width=\"15\" height=\"9\" viewbox=\"0 0 11 7\"><path d=\"M1.414 1.414l4 4 4-4\" fill=\"none\" stroke=\"currentColor\" stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-width=\"2\"\/><\/svg><\/span><\/div>\n              <p class=\"mb-10 mb-lg-0 ml-10 ml-lg-0 font-size-overline-large pr-sm-50\">S\u00e9lection du site et accord foncier<\/p>\n            <\/div>\n                      <div class=\"d-flex flex-row flex-lg-column w-100 w-lg-14 flex-middle\">\n              <div class=\"h-50px w-12px h-lg-12px w-lg-100 mb-lg-15 bg-color-status-unchecked position-relative\"><span class=\"\"><svg width=\"15\" height=\"9\" viewbox=\"0 0 11 7\"><path d=\"M1.414 1.414l4 4 4-4\" fill=\"none\" stroke=\"currentColor\" stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-width=\"2\"\/><\/svg><\/span><\/div>\n              <p class=\"mb-10 mb-lg-0 ml-10 ml-lg-0 font-size-overline-large pr-sm-50\">\u00c9tudes environnementales et agricoles<\/p>\n            <\/div>\n                      <div class=\"d-flex flex-row flex-lg-column w-100 w-lg-14 flex-middle\">\n              <div class=\"h-50px w-12px h-lg-12px w-lg-100 mb-lg-15 bg-color-status-unchecked position-relative\"><span class=\"\"><svg width=\"15\" height=\"9\" viewbox=\"0 0 11 7\"><path d=\"M1.414 1.414l4 4 4-4\" fill=\"none\" stroke=\"currentColor\" stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-width=\"2\"\/><\/svg><\/span><\/div>\n              <p class=\"mb-10 mb-lg-0 ml-10 ml-lg-0 font-size-overline-large pr-sm-50\">Enqu\u00eate publique<\/p>\n            <\/div>\n                      <div class=\"d-flex flex-row flex-lg-column w-100 w-lg-14 flex-middle\">\n              <div class=\"h-50px w-12px h-lg-12px w-lg-100 mb-lg-15 bg-color-status-unchecked position-relative\"><span class=\"\"><svg width=\"15\" height=\"9\" viewbox=\"0 0 11 7\"><path d=\"M1.414 1.414l4 4 4-4\" fill=\"none\" stroke=\"currentColor\" stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-width=\"2\"\/><\/svg><\/span><\/div>\n              <p class=\"mb-10 mb-lg-0 ml-10 ml-lg-0 font-size-overline-large pr-sm-50\">Obtention du permis de construire<\/p>\n            <\/div>\n                      <div class=\"d-flex flex-row flex-lg-column w-100 w-lg-14 flex-middle\">\n              <div class=\"h-50px w-12px h-lg-12px w-lg-100 mb-lg-15 bg-color-status-unchecked position-relative\"><span class=\"\"><svg width=\"15\" height=\"9\" viewbox=\"0 0 11 7\"><path d=\"M1.414 1.414l4 4 4-4\" fill=\"none\" stroke=\"currentColor\" stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-width=\"2\"\/><\/svg><\/span><\/div>\n              <p class=\"mb-10 mb-lg-0 ml-10 ml-lg-0 font-size-overline-large pr-sm-50\">Raccordement et construction<\/p>\n            <\/div>\n                      <div class=\"d-flex flex-row flex-lg-column w-100 w-lg-14 flex-middle\">\n              <div class=\"h-50px w-12px h-lg-12px w-lg-100 mb-lg-15 bg-color-status-unchecked position-relative\"><span class=\"\"><svg width=\"15\" height=\"9\" viewbox=\"0 0 11 7\"><path d=\"M1.414 1.414l4 4 4-4\" fill=\"none\" stroke=\"currentColor\" stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-width=\"2\"\/><\/svg><\/span><\/div>\n              <p class=\"mb-10 mb-lg-0 ml-10 ml-lg-0 font-size-overline-large pr-sm-50\">Exploitation<\/p>\n            <\/div>\n                      <div class=\"d-flex flex-row flex-lg-column w-100 w-lg-14 flex-middle\">\n              <div class=\"h-50px w-12px h-lg-12px w-lg-100 mb-lg-15 bg-color-status-unchecked position-relative\"><span class=\"d-none\"><svg width=\"15\" height=\"9\" viewbox=\"0 0 11 7\"><path d=\"M1.414 1.414l4 4 4-4\" fill=\"none\" stroke=\"currentColor\" stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-width=\"2\"\/><\/svg><\/span><\/div>\n              <p class=\"mb-10 mb-lg-0 ml-10 ml-lg-0 font-size-overline-large \">D\u00e9mant\u00e8lement<\/p>\n            <\/div>\n                  <\/div>\n          <\/div>\n  <\/div>\n\n  <div class=\"pt-60 pt-lg-100\"><\/div>\n<\/section>\n\n\n<section class=\"fifty-fifty align block_acf-block-69fca1f04bb71 block bg-color-white position-relative z-1 overflow-hidden\">\n        <div class=\"pt-60 pt-lg-100\"><\/div>\n\n    \n    <div class=\"fifty-fifty__row\">\n      <div class=\"container \">\n        <div class=\"row align-items-center\">\n                      <div class=\"col-12 col-lg-6 align-self-center fifty-left d-flex flex-column order-2 order-lg-1\">\n                                                                  <h2 class=\"mb-20 \">Ferme solaire des Cazals<\/h2>\n                                                                                                                                                                <div class=\"flex flex-column w-100 line-height-level-6 mb-15 fifty-fifty__text font-size-paragraph-medium  fg-color-navy-text \">\n                    <p>Initi\u00e9 au premier semestre 2024, le projet de ferme agrivolta\u00efque des Cazals est n\u00e9 de la rencontre entre Lightsource bp et plusieurs propri\u00e9taires de parcelles situ\u00e9es \u00e0 Sall\u00e8les Cabard\u00e8s, \u00e0 proximit\u00e9 de l\u2019ancienne d\u00e9chetterie. Ces terrains, laiss\u00e9s en friche et sans activit\u00e9 agricole depuis parfois plus de vingt ans, pr\u00e9sentent aujourd\u2019hui un potentiel de valorisation agricole et \u00e9nerg\u00e9tique.<\/p>\n<p>Sensibles aux enjeux climatiques et aux effets croissants des s\u00e9cheresses sur le territoire, les propri\u00e9taires ont souhait\u00e9 redonner une vocation productive \u00e0 ces parcelles. Dans cette perspective, l\u2019un d\u2019entre eux a mis en relation Lightsource bp avec une \u00e9leveuse ovine locale dont l\u2019exploitation se pr\u00eate naturellement \u00e0 un projet agrivolta\u00efque conciliant production d\u2019\u00e9lectricit\u00e9 renouvelable et maintien d\u2019une activit\u00e9 d\u2019\u00e9levage.<\/p>\n<p>Afin d\u2019assurer une bonne int\u00e9gration territoriale et une information transparente, le projet a \u00e9t\u00e9 pr\u00e9sent\u00e9 aux \u00e9lus et aux services de l\u2019\u00c9tat d\u00e8s sa phase de conception. Les parcelles concern\u00e9es sont aujourd\u2019hui identifi\u00e9es en zone d\u2019acc\u00e9l\u00e9ration des \u00e9nergies renouvelables (ZAENR), classement officialis\u00e9 par arr\u00eat\u00e9 pr\u00e9fectoral le 7 mars 2025. Un p\u00f4le ENR organis\u00e9 par la DDTM de l\u2019Aude le 24 novembre 2025 a \u00e9galement permis de recueillir les pr\u00e9conisations des acteurs du territoire (DDTM, Chambre d\u2019Agriculture, Enedis, etc.).<\/p>\n<p>Le projet pr\u00e9voit le financement, la construction, l\u2019exploitation, la maintenance et le d\u00e9mant\u00e8lement d\u2019une installation agrivolta\u00efque d\u2019une puissance maximale de 4,97 MWc coupl\u00e9e \u00e0 une unit\u00e9 de stockage d\u2019\u00e9nergie de 5 MW. Le projet permettra de produire environ 6 604 MWh par an, soit l\u2019\u00e9quivalent de la consommation annuelle d\u2019environ 3 235 personnes (source : agence ORE, 2 223 kWh\/habitant\/an).<\/p>\n<p>Le d\u00e9p\u00f4t de la demande de permis de construire est envisag\u00e9 \u00e0 la mi 2026. La phase d\u2019instruction comprendra notamment une enqu\u00eate publique, organis\u00e9e courant 2027 sous l\u2019autorit\u00e9 d\u2019un commissaire enqu\u00eateur d\u00e9sign\u00e9 par la pr\u00e9fecture.<\/p>\n\n                  <\/div>\n                                                                                                          <\/div>\n                                <div class=\"col-12 col-lg-6 align-self-center fifty-right d-flex flex-column mb-lg-0 mt-lg-0 order-3 order-lg-1  mt-15 \">\n                                                                                                                <div class=\"flex flex-column w-100 mb-30 fifty-fifty__image\">\n                    <picture><source srcset=\"https:\/\/lightsourcebp.com\/app\/uploads\/2026\/05\/Lightsource-bp_Ferme-Solaire_Cazals_Site-scaled.jpg 2560w, https:\/\/lightsourcebp.com\/app\/uploads\/2026\/05\/Lightsource-bp_Ferme-Solaire_Cazals_Site-300x200.jpg 300w, https:\/\/lightsourcebp.com\/app\/uploads\/2026\/05\/Lightsource-bp_Ferme-Solaire_Cazals_Site-1024x683.jpg 1024w, https:\/\/lightsourcebp.com\/app\/uploads\/2026\/05\/Lightsource-bp_Ferme-Solaire_Cazals_Site-80x53.jpg 80w, https:\/\/lightsourcebp.com\/app\/uploads\/2026\/05\/Lightsource-bp_Ferme-Solaire_Cazals_Site-150x100.jpg 150w, https:\/\/lightsourcebp.com\/app\/uploads\/2026\/05\/Lightsource-bp_Ferme-Solaire_Cazals_Site-450x300.jpg 450w, https:\/\/lightsourcebp.com\/app\/uploads\/2026\/05\/Lightsource-bp_Ferme-Solaire_Cazals_Site-767x511.jpg 767w, https:\/\/lightsourcebp.com\/app\/uploads\/2026\/05\/Lightsource-bp_Ferme-Solaire_Cazals_Site-1000x667.jpg 1000w, https:\/\/lightsourcebp.com\/app\/uploads\/2026\/05\/Lightsource-bp_Ferme-Solaire_Cazals_Site-1200x800.jpg 1200w, https:\/\/lightsourcebp.com\/app\/uploads\/2026\/05\/Lightsource-bp_Ferme-Solaire_Cazals_Site-1600x1066.jpg 1600w, https:\/\/lightsourcebp.com\/app\/uploads\/2026\/05\/Lightsource-bp_Ferme-Solaire_Cazals_Site-1920x1280.jpg 1920w\" sizes=\"100vw\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lightsourcebp.com\/app\/uploads\/2026\/05\/Lightsource-bp_Ferme-Solaire_Cazals_Site-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1706\" class=\"d-flex max-w-100 w-100 h-auto mx-auto fit-cover rounded-10px\"><\/picture>\n                  <\/div>\n                                                                                                                                                  <div class=\"d-inline-flex w-100 button-container mb-15\">\n                    <a class=\"button button--gradient my-0 mr-auto\" href=\"https:\/\/lightsourcebp.com\/app\/uploads\/2026\/05\/Lightsource-bp_Ferme-Solaire_Cazals_dossier-info.pdf\" target=\"_blank\"><span>Projet solaire des Cazals | Dossier d&#8217;informations<\/span> <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" fill=\"none\"><path stroke=\"currentColor\" stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-width=\"2\" d=\"M21 15v4a2 2 0 0 1-2 2H5a2 2 0 0 1-2-2v-4m4-5 5 5 5-5m-5 5V3\"\/><\/svg><\/a>\n                  <\/div>\n                                                                                                          <\/div>\n                  <\/div>\n      <\/div>\n    <\/div>\n\n  <div class=\"pt-60 pt-lg-100\"><\/div>\n  <\/section>\n\n\n<section class=\"fifty-fifty align block_acf-block-69fb4423013a0 block bg-color-orange-3-percent position-relative z-1 overflow-hidden\">\n        <div class=\"pt-60 pt-lg-100\"><\/div>\n\n          <img decoding=\"async\" class=\"position-absolute top-n20 right-n125 right-sm-n80 right-md-n45 right-xl-n32 rotate-230 -z-1\" src=\"https:\/\/lightsourcebp.com\/app\/themes\/lightsourcebp-theme\/dist\/images\/global\/background-swirls_4744d58b.png\" alt=\"\" \/>\n    \n    <div class=\"fifty-fifty__row\">\n      <div class=\"container \">\n        <div class=\"row align-items-center\">\n                      <div class=\"col-12 col-lg-6 col-xl-7 align-self-center fifty-left d-flex flex-column order-2 order-lg-1\">\n                                                                  <h2 class=\"mb-20 \">Les \u00e9tapes cl\u00e9s du projet<\/h2>\n                                                                                                                                                                <div class=\"flex flex-column w-100 line-height-level-6 mb-15 fifty-fifty__text font-size-paragraph-medium  fg-color-navy-text \">\n                    <p style=\"font-weight: 400;\">1<sup>er<\/sup> semestre 2024\u00a0: lancement du projet de ferme agrivolta\u00efque des Cazals<\/p>\n<p style=\"font-weight: 400;\">24 novembre 2025\u00a0: r\u00e9union du p\u00f4le ENR organis\u00e9 par la DDTM de l\u2019Aude pour recueillir les pr\u00e9conisations des acteurs du territoire<\/p>\n<p style=\"font-weight: 400;\">Mi-2026\u00a0: d\u00e9p\u00f4t de la demande de permis de construire<\/p>\n<p style=\"font-weight: 400;\">Courant 2027\u00a0: enqu\u00eate publique sous l\u2019autorit\u00e9 d\u2019un commissaire\u2011enqu\u00eateur d\u00e9sign\u00e9 par la pr\u00e9fecture<\/p>\n\n                  <\/div>\n                                                                                                          <\/div>\n                            <\/div>\n      <\/div>\n    <\/div>\n\n  <div class=\"pt-60 pt-lg-100\"><\/div>\n  <\/section>\n\n\n<section class=\"fifty-fifty align block_acf-block-69fb419b835c6 block bg-color-white position-relative z-1 overflow-hidden\">\n        <div class=\"pt-60 pt-lg-100\"><\/div>\n\n    \n    <div class=\"fifty-fifty__row\">\n      <div class=\"container \">\n        <div class=\"row align-items-center\">\n                      <div class=\"col-12 col-lg-6 align-self-center fifty-left d-flex flex-column order-2 order-lg-1\">\n                                                                  <h2 class=\"mb-20 \">Informations et ressources<\/h2>\n                                                                                                                                                                <div class=\"flex flex-column w-100 line-height-level-6 mb-15 fifty-fifty__text font-size-paragraph-medium  fg-color-navy-text \">\n                    <p style=\"font-weight: 400;\">Vous souhaitez en savoir plus sur Lightsource bp, notre d\u00e9marche et notre approche \u00e0 360\u00b0\u00a0? Vous trouverez toutes ces informations ici\u00a0:<\/p>\n<p style=\"font-weight: 400;\"><a href=\"https:\/\/lightsourcebp.com\/fr\/partenariats\/agriculteurs-et-eleveurs\/\">Lightsource bp et l\u2019agrivolta\u00efsme<\/a><\/p>\n<p style=\"font-weight: 400;\"><a href=\"https:\/\/lightsourcebp.com\/fr\/developpement-durable\/\">Notre cadre de d\u00e9veloppement durable<\/a><\/p>\n<p style=\"font-weight: 400;\"><a href=\"https:\/\/lightsourcebp.com\/fr\/developpement-durable\/biodiversite-agriculture-durable\/\">Nos actions en faveur de la biodiversit\u00e9<\/a><\/p>\n<p style=\"font-weight: 400;\"><a href=\"https:\/\/lightsourcebp.com\/fr\/partenariats\/location-terre-agricole-panneaux-photovoltaiques\/\">Louer son terrain pour un projet agrivolta\u00efque<\/a><\/p>\n\n                  <\/div>\n                                                                                                          <\/div>\n                            <\/div>\n      <\/div>\n    <\/div>\n\n  <div class=\"pt-60 pt-lg-100\"><\/div>\n  <\/section>\n\n\n<section class=\"contact-form align block_acf-block-69fb419bcb555 block call-to-action\">\n  \n  <div class=\"container-fluid z-2\">\n    <div class=\"row\">\n      <div class=\"col-12 col-lg-6 px-0 position-relative\">\n        <picture><source srcset=\"https:\/\/lightsourcebp.com\/app\/uploads\/2022\/12\/Contact-form-1.jpg 790w, https:\/\/lightsourcebp.com\/app\/uploads\/2022\/12\/Contact-form-1-269x300.jpg 269w, https:\/\/lightsourcebp.com\/app\/uploads\/2022\/12\/Contact-form-1-80x89.jpg 80w, https:\/\/lightsourcebp.com\/app\/uploads\/2022\/12\/Contact-form-1-150x167.jpg 150w, https:\/\/lightsourcebp.com\/app\/uploads\/2022\/12\/Contact-form-1-300x334.jpg 300w, https:\/\/lightsourcebp.com\/app\/uploads\/2022\/12\/Contact-form-1-450x501.jpg 450w, https:\/\/lightsourcebp.com\/app\/uploads\/2022\/12\/Contact-form-1-767x854.jpg 767w\" sizes=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lightsourcebp.com\/app\/uploads\/2022\/12\/Contact-form-1.jpg\" alt=\"sun setting over solar panels\" width=\"790\" height=\"880\" class=\"w-101 h-auto h-sm-100 object-fit-cover ml-15px\"><\/picture>\n        <div class=\"contact-form__overlap-text position-absolute bg-color-white top-35px top-sm-100px left-5 left-md-15 w-90 w-md-70 py-50 px-15 px-md-65\">\n                      <h2>Contactez-nous !<br>\n<\/h2>\n                    <p class=\"line-height-level-6 font-size-paragraph-large\">Vous souhaitez obtenir davantage de renseignements sur notre projet de ferme agrivolta\u00efque ? Partager votre avis ou \u00e9mettre des recommandations ? Contactez-nous par e-mail ou via le formulaire ci-contre, nous serons ravis d&#039;\u00e9changer avec vous.<\/p>\n                      <a class=\"d-flex flex-row flex-middle fg-color-orange text-decoration-none text-decoration-underline-hover font-weight-bold\" href=\"mailto:contact.fr@lightsourcebp.com\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"25\" fill=\"none\"><path stroke=\"#E0D9E9\" stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-width=\"2\" d=\"M4 4.54h16c1.1 0 2 .9 2 2v12c0 1.1-.9 2-2 2H4c-1.1 0-2-.9-2-2v-12c0-1.1.9-2 2-2Z\"\/><path stroke=\"#E0D9E9\" stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-width=\"2\" d=\"m22 6.54-10 7-10-7\"\/><\/svg>\n <span class=\"ml-15\">contact.fr@lightsourcebp.com<\/span><\/a>\n                            <\/div>\n      <\/div>\n      <div class=\"col-12 col-lg-6 bg-color-gradient fg-color-navy position-relative z-1 overflow-hidden\">\n\n        <img decoding=\"async\" class=\"position-absolute top-n20 right-n125 right-sm-n100 right-md-n80 right-xl-n68 rotate-230 -z-1\" src=\"https:\/\/lightsourcebp.com\/app\/themes\/lightsourcebp-theme\/dist\/images\/global\/background-swirls-alt-red_4744d58b.png\" alt=\"\" \/>\n\n        <div class=\"d-flex flex-column flex-center px-15 px-md-100 py-40 py-lg-100\">\n                      <div class=\"row flex-center\">\n              <p class=\"fg-color-white font-weight-bold mb-30\">*\u5fc5\u9808\u586b\u5beb<\/p>\n              <form novalidate action=\"https:\/\/lightsourcebp.com\/tw\/forms\/contact-form\/#contact-form_acf-block-69fb419bcb555\" class=\"form d-flex flex-wrap text-left \" data-id=\"239201\" enctype=\"multipart\/form-data\">\n\n          <div id=\"type-de-demande\" class=\"form__input-row d-flex flex-column mb-20 position-relative form__input-row--full  form__input-row--select \">\n          <label class=\"form__label user-select-none mb-12 font-weight-bold font-size-paragraph-small fg-color-white\" for=\"type-de-demande_239201\">Type de demande<span class=\"form__required-indicator\">*<\/span><\/label>\n    \n    <div class=\"position-relative w-100\">\n  <select\n    id=\"type-de-demande_239201\"\n    class=\"form__select form__select--unselected pl-20 pr-50 py-14\"\n    name=\"type-de-demande\"\n    data-field-label=\"Type de demande&lt;span class=&quot;form__required-indicator&quot;&gt;*&lt;\/span&gt;\"\n  \/>\n    <option value=\"\" disabled 1>Please choose<\/option>\n          <option value=\"Demande de location de terrain\" >Demande de location de terrain<\/option>\n          <option value=\"Demande concernant les contrats d\u2019achat d\u2019\u00e9lectricit\u00e9 (PPA) ou l\u2019achat d\u2019\u00e9nergie\" >Demande concernant les contrats d\u2019achat d\u2019\u00e9lectricit\u00e9 (PPA) ou l\u2019achat d\u2019\u00e9nergie<\/option>\n          <option value=\"Demande concernant le projet\" >Demande concernant le projet<\/option>\n          <option value=\"Demande g\u00e9n\u00e9rale\" >Demande g\u00e9n\u00e9rale<\/option>\n          <option value=\"Demande concernant les carri\u00e8res\" >Demande concernant les carri\u00e8res<\/option>\n      <\/select>\n  <div class=\"pointer-events-none position-absolute d-flex flex-center flex-middle w-70px h-100 top-1px right-0 fg-color-white\">\n    \n  <\/div>\n<\/div>\n  <\/div>\n\n          <div id=\"organisation\" class=\"form__input-row d-flex flex-column mb-20 position-relative form__input-row--full  form__input-row--text \">\n          <label class=\"form__label user-select-none mb-12 font-weight-bold font-size-paragraph-small fg-color-white\" for=\"organisation_239201\">Organisation<\/label>\n    \n    <input\n  id=\"organisation_239201\"\n  class=\"form__input h-55px w-100 px-20 py-10\"\n  type=\"text\"\n  name=\"organisation\"\n  placeholder=\"\"\n  value=\"\"\n\/>\n  <\/div>\n\n          <div id=\"nom\" class=\"form__input-row d-flex flex-column mb-20 position-relative form__input-row--full  form__input-row--text \">\n          <label class=\"form__label user-select-none mb-12 font-weight-bold font-size-paragraph-small fg-color-white\" for=\"nom_239201\">Nom<span class=\"form__required-indicator\">*<\/span><\/label>\n    \n    <input\n  id=\"nom_239201\"\n  class=\"form__input h-55px w-100 px-20 py-10\"\n  type=\"text\"\n  name=\"nom\"\n  placeholder=\"\"\n  value=\"\"\n\/>\n  <\/div>\n\n          <div id=\"adresse-e-mail\" class=\"form__input-row d-flex flex-column mb-20 position-relative form__input-row--full  form__input-row--text \">\n          <label class=\"form__label user-select-none mb-12 font-weight-bold font-size-paragraph-small fg-color-white\" for=\"adresse-e-mail_239201\">Adresse e-mail<span class=\"form__required-indicator\">*<\/span><\/label>\n    \n    <input\n  id=\"adresse-e-mail_239201\"\n  class=\"form__input h-55px w-100 px-20 py-10\"\n  type=\"text\"\n  name=\"adresse-e-mail\"\n  placeholder=\"\"\n  value=\"\"\n\/>\n  <\/div>\n\n          <div id=\"numero-de-telephone\" class=\"form__input-row d-flex flex-column mb-20 position-relative form__input-row--full  form__input-row--text \">\n          <label class=\"form__label user-select-none mb-12 font-weight-bold font-size-paragraph-small fg-color-white\" for=\"numero-de-telephone_239201\">Num\u00e9ro de t\u00e9l\u00e9phone<\/label>\n    \n    <input\n  id=\"numero-de-telephone_239201\"\n  class=\"form__input h-55px w-100 px-20 py-10\"\n  type=\"text\"\n  name=\"numero-de-telephone\"\n  placeholder=\"\"\n  value=\"\"\n\/>\n  <\/div>\n\n          <div id=\"message\" class=\"form__input-row d-flex flex-column mb-20 position-relative form__input-row--full  form__input-row--text \">\n          <label class=\"form__label user-select-none mb-12 font-weight-bold font-size-paragraph-small fg-color-white\" for=\"message_239201\">Message<span class=\"form__required-indicator\">*<\/span><\/label>\n    \n    <input\n  id=\"message_239201\"\n  class=\"form__input h-55px w-100 px-20 py-10\"\n  type=\"text\"\n  name=\"message\"\n  placeholder=\"\"\n  value=\"\"\n\/>\n  <\/div>\n\n    \n    \n    <div class=\"form__input-row form__input-row--recaptcha form__input-row--full form__input-row--last relative d-flex justify-content-sm-center\">\n      <div name=\"recaptcha\" class=\"g-recaptcha\"><\/div>\n    <\/div>\n\n    <div class=\"d-flex mt-10\">\n      <div class=\"d-flex flex-column\">\n        \n        <div class=\"d-inline-flex w-100 button-container mt-20\">\n          <button class=\"form__submit-button button button--gradient my-0 mr-auto my-0\" href=\"\"><span class=\"button__text\">Envoyer<\/span> <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"25\" fill=\"none\"><path stroke=\"currentColor\" stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-width=\"2\" d=\"m20 4.54-9 9m9-9-5.6 16-3.2-7.2-7.2-3.2 16-5.6Z\"\/><\/svg>\n<\/button>\n        <\/div>\n\n      <\/div>\n    <\/div>\n  <\/form>\n            <\/div>\n                  <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n<\/section>\n\n","protected":false},"featured_media":484897,"parent":0,"menu_order":0,"template":"","project_status":[24],"project_region":[1007],"project_sizes":[31],"project_type":[],"class_list":["post-484895","project","type-project","status-publish","has-post-thumbnail","hentry","project_status-development","project_region-france","project_sizes-up-to-100mw"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/lightsourcebp.com\/tw\/wp-json\/wp\/v2\/project\/484895","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lightsourcebp.com\/tw\/wp-json\/wp\/v2\/project"}],"about":[{"href":"https:\/\/lightsourcebp.com\/tw\/wp-json\/wp\/v2\/types\/project"}],"version-history":[{"count":9,"href":"https:\/\/lightsourcebp.com\/tw\/wp-json\/wp\/v2\/project\/484895\/revisions"}],"predecessor-version":[{"id":485000,"href":"https:\/\/lightsourcebp.com\/tw\/wp-json\/wp\/v2\/project\/484895\/revisions\/485000"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lightsourcebp.com\/tw\/wp-json\/wp\/v2\/media\/484897"}],"wp:attachment":[{"href":"https:\/\/lightsourcebp.com\/tw\/wp-json\/wp\/v2\/media?parent=484895"}],"wp:term":[{"taxonomy":"project_status","embeddable":true,"href":"https:\/\/lightsourcebp.com\/tw\/wp-json\/wp\/v2\/project_status?post=484895"},{"taxonomy":"project_region","embeddable":true,"href":"https:\/\/lightsourcebp.com\/tw\/wp-json\/wp\/v2\/project_region?post=484895"},{"taxonomy":"project_sizes","embeddable":true,"href":"https:\/\/lightsourcebp.com\/tw\/wp-json\/wp\/v2\/project_sizes?post=484895"},{"taxonomy":"project_type","embeddable":true,"href":"https:\/\/lightsourcebp.com\/tw\/wp-json\/wp\/v2\/project_type?post=484895"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}